{"id":4529,"date":"2020-05-19T17:26:18","date_gmt":"2020-05-19T15:26:18","guid":{"rendered":"https:\/\/www.villamiami.fr\/die-zimmer\/"},"modified":"2022-09-27T12:37:27","modified_gmt":"2022-09-27T10:37:27","slug":"die-zimmer","status":"publish","type":"page","link":"https:\/\/www.villamiami.fr\/de\/die-zimmer\/","title":{"rendered":"Die Zimmer"},"content":{"rendered":"<p>[vc_row][vc_column]<div style=\"background-color:;height: 150px\" class=\"nicdark_section  \"><\/div> <h1 style=\"color:;padding:px;text-align:center;font-size:50px;line-height:px;letter-spacing: px;font-weight:lighter\" class=\"  nd_options_font_size_40_important_all_iphone nd_options_line_height_40_important_all_iphone nd_options_first_font \">SUITEN &amp; ZIMMER<\/h1> <div style=\"background-color:;height: 30px\" class=\"nicdark_section  \"><\/div> <p style=\"color:;padding:px;text-align:center;font-size:px;line-height:px;letter-spacing: 2px;font-weight:lighter\" class=\"  nd_options_font_size_40_important_all_iphone nd_options_line_height_40_important_all_iphone nd_options_second_font \">- VILLA MIAMI -<\/p> [\/vc_column][\/vc_row][vc_row][vc_column]<div style=\"background-color:;height: 25px\" class=\"nicdark_section  \"><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center;\">Entdecken Sie unsere 2 Suiten mit Whirlpool-Badewanne und unsere 3 Schlafzimmer :<br \/>\n<strong>Die Matisse-Suite, <\/strong><strong>die Vegetarische Suite, <\/strong><\/p>\n<p style=\"text-align: center;\"><strong>die Mineralien, die Schokolade und das Tauchen<\/strong><\/p>\n<p>[\/vc_column_text]<div style=\"background-color:;height: 5px\" class=\"nicdark_section  \"><\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row_content_no_spaces&#8220; css=&#8220;.vc_custom_1589902385613{margin-top: 30px !important;margin-bottom: 100px !important;}&#8220;][vc_column css=&#8220;.vc_custom_1491985274415{padding-right: 30px !important;padding-left: 30px !important;}&#8220;]\n\n\t<script type=\"text\/javascript\">\n    \/\/<![CDATA[\n    \n    jQuery(document).ready(function() {\n\n      \/\/START masonry\n      jQuery(function ($) {\n        \n        \/\/Masonry\n    \t\tvar $nd_booking_masonry_content = $(\".nd_booking_masonry_content\").imagesLoaded( function() {\n    \t\t  \/\/ init Masonry after all images have loaded\n    \t\t  $nd_booking_masonry_content.masonry({\n    \t\t    itemSelector: \".nd_booking_masonry_item\"\n    \t\t  });\n    \t\t});\n\n      });\n      \/\/END masonry\n\n    });\n\n    \/\/]]>\n  <\/script>\n\n<div class=\" nd_booking_rooms_component_l5 nd_booking_section nd_booking_masonry_content rooms-l5-home1 \">\n\n<div id=\"nd_booking_archive_cpt_1_single_5138\" class=\" nd_booking_rooms_component_l5  nd_booking_masonry_item nd_booking_width_33_percentage nd_booking_float_left nd_booking_width_100_percentage_responsive\">\n\n    <div class=\"nd_booking_section nd_booking_padding_15 nd_booking_box_sizing_border_box\">\n\n        <div class=\"nd_booking_section nd_booking_border_1_solid_grey nd_booking_bg_white\">\n            \n            \n\n        <div class=\"nd_booking_section nd_booking_position_relative\">\n\n            <img decoding=\"async\" alt=\"\" class=\"nd_booking_section\" src=\"https:\/\/www.villamiami.fr\/wp-content\/uploads\/2020\/05\/MATISSE-PHOTO-PRINCIPALE-DES-CHAMBRES-1024x768.png\">\n\n            <div class=\"nd_booking_bg_greydark_alpha_gradient_3 nd_booking_position_absolute nd_booking_left_0 nd_booking_height_100_percentage nd_booking_width_100_percentage nd_booking_padding_30 nd_booking_box_sizing_border_box\">\n                \n                <div class=\"nd_booking_position_absolute nd_booking_top_20 nd_booking_left_0 nd_booking_width_100_percentage\">\n                    <div class=\"nd_booking_section nd_booking_text_align_center\">\n                        <a style=\"background-color: #000;\" href=\"https:\/\/www.villamiami.fr\/de\/rooms\/matisse-suite-41\/\" class=\"nd_booking_padding_10_20 nd_booking_text_transform_uppercase nd_options_second_font_important nd_booking_border_radius_0_important nd_options_color_white nd_booking_cursor_pointer nd_booking_display_inline_block nd_booking_font_size_12 nd_booking_letter_spacing_2\">Suite Matisse &#8211; 41m\u00b2<\/a>\n                    <\/div>\n                <\/div>\n\n                <div class=\"nd_booking_position_absolute nd_booking_bottom_20 nd_booking_left_0 nd_booking_width_100_percentage\">\n\n\n                    <div class=\"nd_booking_section nd_booking_text_align_center nd_booking_display_none_iphone_port\">\n                        <div class=\"nd_booking_display_table nd_booking_margin_auto\">\n                            <img decoding=\"async\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"23\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-user-white.png\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\"> Guests<\/p>\n                            <img decoding=\"async\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_margin_left_20 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"20\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-plan-white.png\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\"> m\u00b2<\/p>\n                            <img decoding=\"async\" style=\"padding-bottom:4px;\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_margin_left_20 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"20\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-star-empty-white.svg\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\">From  \u20ac<\/p>\n                        <\/div>\n                    <\/div> \n\n                <\/div>\n            <\/div>\n\n        <\/div>\n\n    \n\n        <\/div>\n\n    <\/div>\n\n<\/div>\n\n<div id=\"nd_booking_archive_cpt_1_single_5190\" class=\" nd_booking_rooms_component_l5  nd_booking_masonry_item nd_booking_width_33_percentage nd_booking_float_left nd_booking_width_100_percentage_responsive\">\n\n    <div class=\"nd_booking_section nd_booking_padding_15 nd_booking_box_sizing_border_box\">\n\n        <div class=\"nd_booking_section nd_booking_border_1_solid_grey nd_booking_bg_white\">\n            \n            \n\n        <div class=\"nd_booking_section nd_booking_position_relative\">\n\n            <img decoding=\"async\" alt=\"\" class=\"nd_booking_section\" src=\"https:\/\/www.villamiami.fr\/wp-content\/uploads\/2020\/08\/VILLA-PISCINE-7-scaled-1024x683.jpg\">\n\n            <div class=\"nd_booking_bg_greydark_alpha_gradient_3 nd_booking_position_absolute nd_booking_left_0 nd_booking_height_100_percentage nd_booking_width_100_percentage nd_booking_padding_30 nd_booking_box_sizing_border_box\">\n                \n                <div class=\"nd_booking_position_absolute nd_booking_top_20 nd_booking_left_0 nd_booking_width_100_percentage\">\n                    <div class=\"nd_booking_section nd_booking_text_align_center\">\n                        <a style=\"background-color: #000;\" href=\"https:\/\/www.villamiami.fr\/de\/rooms\/die-villa-mieten\/\" class=\"nd_booking_padding_10_20 nd_booking_text_transform_uppercase nd_options_second_font_important nd_booking_border_radius_0_important nd_options_color_white nd_booking_cursor_pointer nd_booking_display_inline_block nd_booking_font_size_12 nd_booking_letter_spacing_2\">Die Villa mieten<\/a>\n                    <\/div>\n                <\/div>\n\n                <div class=\"nd_booking_position_absolute nd_booking_bottom_20 nd_booking_left_0 nd_booking_width_100_percentage\">\n\n\n                    <div class=\"nd_booking_section nd_booking_text_align_center nd_booking_display_none_iphone_port\">\n                        <div class=\"nd_booking_display_table nd_booking_margin_auto\">\n                            <img decoding=\"async\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"23\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-user-white.png\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\">16 Guests<\/p>\n                            <img decoding=\"async\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_margin_left_20 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"20\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-plan-white.png\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\">360 m\u00b2<\/p>\n                            <img decoding=\"async\" style=\"padding-bottom:4px;\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_margin_left_20 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"20\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-star-empty-white.svg\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\">From  \u20ac<\/p>\n                        <\/div>\n                    <\/div> \n\n                <\/div>\n            <\/div>\n\n        <\/div>\n\n    \n\n        <\/div>\n\n    <\/div>\n\n<\/div>\n\n<div id=\"nd_booking_archive_cpt_1_single_5137\" class=\" nd_booking_rooms_component_l5  nd_booking_masonry_item nd_booking_width_33_percentage nd_booking_float_left nd_booking_width_100_percentage_responsive\">\n\n    <div class=\"nd_booking_section nd_booking_padding_15 nd_booking_box_sizing_border_box\">\n\n        <div class=\"nd_booking_section nd_booking_border_1_solid_grey nd_booking_bg_white\">\n            \n            \n\n        <div class=\"nd_booking_section nd_booking_position_relative\">\n\n            <img decoding=\"async\" alt=\"\" class=\"nd_booking_section\" src=\"https:\/\/www.villamiami.fr\/wp-content\/uploads\/2020\/05\/VEGETALE-CHAMBRE-BAIE-VITREE-1024x768.jpg\">\n\n            <div class=\"nd_booking_bg_greydark_alpha_gradient_3 nd_booking_position_absolute nd_booking_left_0 nd_booking_height_100_percentage nd_booking_width_100_percentage nd_booking_padding_30 nd_booking_box_sizing_border_box\">\n                \n                <div class=\"nd_booking_position_absolute nd_booking_top_20 nd_booking_left_0 nd_booking_width_100_percentage\">\n                    <div class=\"nd_booking_section nd_booking_text_align_center\">\n                        <a style=\"background-color: #6ab1bf;\" href=\"https:\/\/www.villamiami.fr\/de\/rooms\/pflanzen-suite\/\" class=\"nd_booking_padding_10_20 nd_booking_text_transform_uppercase nd_options_second_font_important nd_booking_border_radius_0_important nd_options_color_white nd_booking_cursor_pointer nd_booking_display_inline_block nd_booking_font_size_12 nd_booking_letter_spacing_2\">Pflanzensuite &#8211; 30m\u00b2<\/a>\n                    <\/div>\n                <\/div>\n\n                <div class=\"nd_booking_position_absolute nd_booking_bottom_20 nd_booking_left_0 nd_booking_width_100_percentage\">\n\n\n                    <div class=\"nd_booking_section nd_booking_text_align_center nd_booking_display_none_iphone_port\">\n                        <div class=\"nd_booking_display_table nd_booking_margin_auto\">\n                            <img decoding=\"async\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"23\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-user-white.png\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\"> Guests<\/p>\n                            <img decoding=\"async\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_margin_left_20 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"20\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-plan-white.png\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\"> m\u00b2<\/p>\n                            <img decoding=\"async\" style=\"padding-bottom:4px;\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_margin_left_20 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"20\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-star-empty-white.svg\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\">From  \u20ac<\/p>\n                        <\/div>\n                    <\/div> \n\n                <\/div>\n            <\/div>\n\n        <\/div>\n\n    \n\n        <\/div>\n\n    <\/div>\n\n<\/div>\n\n<div id=\"nd_booking_archive_cpt_1_single_5178\" class=\" nd_booking_rooms_component_l5  nd_booking_masonry_item nd_booking_width_33_percentage nd_booking_float_left nd_booking_width_100_percentage_responsive\">\n\n    <div class=\"nd_booking_section nd_booking_padding_15 nd_booking_box_sizing_border_box\">\n\n        <div class=\"nd_booking_section nd_booking_border_1_solid_grey nd_booking_bg_white\">\n            \n            \n\n        <div class=\"nd_booking_section nd_booking_position_relative\">\n\n            <img decoding=\"async\" alt=\"\" class=\"nd_booking_section\" src=\"https:\/\/www.villamiami.fr\/wp-content\/uploads\/2020\/05\/PLONGEE-INT-BAIE-VITREE-1024x768.png\">\n\n            <div class=\"nd_booking_bg_greydark_alpha_gradient_3 nd_booking_position_absolute nd_booking_left_0 nd_booking_height_100_percentage nd_booking_width_100_percentage nd_booking_padding_30 nd_booking_box_sizing_border_box\">\n                \n                <div class=\"nd_booking_position_absolute nd_booking_top_20 nd_booking_left_0 nd_booking_width_100_percentage\">\n                    <div class=\"nd_booking_section nd_booking_text_align_center\">\n                        <a style=\"background-color: #6ab1bf;\" href=\"https:\/\/www.villamiami.fr\/de\/rooms\/das-tauchen\/\" class=\"nd_booking_padding_10_20 nd_booking_text_transform_uppercase nd_options_second_font_important nd_booking_border_radius_0_important nd_options_color_white nd_booking_cursor_pointer nd_booking_display_inline_block nd_booking_font_size_12 nd_booking_letter_spacing_2\">La Plong\u00e9e &#8211; 25m\u00b2<\/a>\n                    <\/div>\n                <\/div>\n\n                <div class=\"nd_booking_position_absolute nd_booking_bottom_20 nd_booking_left_0 nd_booking_width_100_percentage\">\n\n\n                    <div class=\"nd_booking_section nd_booking_text_align_center nd_booking_display_none_iphone_port\">\n                        <div class=\"nd_booking_display_table nd_booking_margin_auto\">\n                            <img decoding=\"async\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"23\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-user-white.png\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\"> Guests<\/p>\n                            <img decoding=\"async\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_margin_left_20 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"20\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-plan-white.png\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\"> m\u00b2<\/p>\n                            <img decoding=\"async\" style=\"padding-bottom:4px;\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_margin_left_20 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"20\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-star-empty-white.svg\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\">From  \u20ac<\/p>\n                        <\/div>\n                    <\/div> \n\n                <\/div>\n            <\/div>\n\n        <\/div>\n\n    \n\n        <\/div>\n\n    <\/div>\n\n<\/div>\n\n<div id=\"nd_booking_archive_cpt_1_single_5749\" class=\" nd_booking_rooms_component_l5  nd_booking_masonry_item nd_booking_width_33_percentage nd_booking_float_left nd_booking_width_100_percentage_responsive\">\n\n    <div class=\"nd_booking_section nd_booking_padding_15 nd_booking_box_sizing_border_box\">\n\n        <div class=\"nd_booking_section nd_booking_border_1_solid_grey nd_booking_bg_white\">\n            \n            \n\n        <div class=\"nd_booking_section nd_booking_position_relative\">\n\n            <img decoding=\"async\" alt=\"\" class=\"nd_booking_section\" src=\"https:\/\/www.villamiami.fr\/wp-content\/uploads\/2023\/04\/CAVEAU-INT-ENTREE-1024x768.jpeg\">\n\n            <div class=\"nd_booking_bg_greydark_alpha_gradient_3 nd_booking_position_absolute nd_booking_left_0 nd_booking_height_100_percentage nd_booking_width_100_percentage nd_booking_padding_30 nd_booking_box_sizing_border_box\">\n                \n                <div class=\"nd_booking_position_absolute nd_booking_top_20 nd_booking_left_0 nd_booking_width_100_percentage\">\n                    <div class=\"nd_booking_section nd_booking_text_align_center\">\n                        <a style=\"background-color: #6ab1bf;\" href=\"https:\/\/www.villamiami.fr\/de\/rooms\/die-gruft\/\" class=\"nd_booking_padding_10_20 nd_booking_text_transform_uppercase nd_options_second_font_important nd_booking_border_radius_0_important nd_options_color_white nd_booking_cursor_pointer nd_booking_display_inline_block nd_booking_font_size_12 nd_booking_letter_spacing_2\">La Caveau &#8211; 21m\u00b2<\/a>\n                    <\/div>\n                <\/div>\n\n                <div class=\"nd_booking_position_absolute nd_booking_bottom_20 nd_booking_left_0 nd_booking_width_100_percentage\">\n\n\n                    <div class=\"nd_booking_section nd_booking_text_align_center nd_booking_display_none_iphone_port\">\n                        <div class=\"nd_booking_display_table nd_booking_margin_auto\">\n                            <img decoding=\"async\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"23\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-user-white.png\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\">2 Guests<\/p>\n                            <img decoding=\"async\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_margin_left_20 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"20\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-plan-white.png\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\">21 m\u00b2<\/p>\n                            <img decoding=\"async\" style=\"padding-bottom:4px;\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_margin_left_20 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"20\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-star-empty-white.svg\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\">From  \u20ac<\/p>\n                        <\/div>\n                    <\/div> \n\n                <\/div>\n            <\/div>\n\n        <\/div>\n\n    \n\n        <\/div>\n\n    <\/div>\n\n<\/div>\n\n<div id=\"nd_booking_archive_cpt_1_single_5198\" class=\" nd_booking_rooms_component_l5  nd_booking_masonry_item nd_booking_width_33_percentage nd_booking_float_left nd_booking_width_100_percentage_responsive\">\n\n    <div class=\"nd_booking_section nd_booking_padding_15 nd_booking_box_sizing_border_box\">\n\n        <div class=\"nd_booking_section nd_booking_border_1_solid_grey nd_booking_bg_white\">\n            \n            \n\n        <div class=\"nd_booking_section nd_booking_position_relative\">\n\n            <img decoding=\"async\" alt=\"\" class=\"nd_booking_section\" src=\"https:\/\/www.villamiami.fr\/wp-content\/uploads\/2020\/05\/CHOCOLAT-INT-BAIE-VITREE-1024x768.png\">\n\n            <div class=\"nd_booking_bg_greydark_alpha_gradient_3 nd_booking_position_absolute nd_booking_left_0 nd_booking_height_100_percentage nd_booking_width_100_percentage nd_booking_padding_30 nd_booking_box_sizing_border_box\">\n                \n                <div class=\"nd_booking_position_absolute nd_booking_top_20 nd_booking_left_0 nd_booking_width_100_percentage\">\n                    <div class=\"nd_booking_section nd_booking_text_align_center\">\n                        <a style=\"background-color: #6ab1bf;\" href=\"https:\/\/www.villamiami.fr\/de\/rooms\/die-schokolade\/\" class=\"nd_booking_padding_10_20 nd_booking_text_transform_uppercase nd_options_second_font_important nd_booking_border_radius_0_important nd_options_color_white nd_booking_cursor_pointer nd_booking_display_inline_block nd_booking_font_size_12 nd_booking_letter_spacing_2\">La Chocolat &#8211; 25m\u00b2<\/a>\n                    <\/div>\n                <\/div>\n\n                <div class=\"nd_booking_position_absolute nd_booking_bottom_20 nd_booking_left_0 nd_booking_width_100_percentage\">\n\n\n                    <div class=\"nd_booking_section nd_booking_text_align_center nd_booking_display_none_iphone_port\">\n                        <div class=\"nd_booking_display_table nd_booking_margin_auto\">\n                            <img decoding=\"async\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"23\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-user-white.png\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\">2 Guests<\/p>\n                            <img decoding=\"async\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_margin_left_20 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"20\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-plan-white.png\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\">25 m\u00b2<\/p>\n                            <img decoding=\"async\" style=\"padding-bottom:4px;\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_margin_left_20 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"20\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-star-empty-white.svg\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\">From 250 \u20ac<\/p>\n                        <\/div>\n                    <\/div> \n\n                <\/div>\n            <\/div>\n\n        <\/div>\n\n    \n\n        <\/div>\n\n    <\/div>\n\n<\/div>\n\n<div id=\"nd_booking_archive_cpt_1_single_5192\" class=\" nd_booking_rooms_component_l5  nd_booking_masonry_item nd_booking_width_33_percentage nd_booking_float_left nd_booking_width_100_percentage_responsive\">\n\n    <div class=\"nd_booking_section nd_booking_padding_15 nd_booking_box_sizing_border_box\">\n\n        <div class=\"nd_booking_section nd_booking_border_1_solid_grey nd_booking_bg_white\">\n            \n            \n\n        <div class=\"nd_booking_section nd_booking_position_relative\">\n\n            <img decoding=\"async\" alt=\"\" class=\"nd_booking_section\" src=\"https:\/\/www.villamiami.fr\/wp-content\/uploads\/2020\/05\/IMG_4523-1024x768.jpg\">\n\n            <div class=\"nd_booking_bg_greydark_alpha_gradient_3 nd_booking_position_absolute nd_booking_left_0 nd_booking_height_100_percentage nd_booking_width_100_percentage nd_booking_padding_30 nd_booking_box_sizing_border_box\">\n                \n                <div class=\"nd_booking_position_absolute nd_booking_top_20 nd_booking_left_0 nd_booking_width_100_percentage\">\n                    <div class=\"nd_booking_section nd_booking_text_align_center\">\n                        <a style=\"background-color: #000;\" href=\"https:\/\/www.villamiami.fr\/de\/rooms\/die-mineralische\/\" class=\"nd_booking_padding_10_20 nd_booking_text_transform_uppercase nd_options_second_font_important nd_booking_border_radius_0_important nd_options_color_white nd_booking_cursor_pointer nd_booking_display_inline_block nd_booking_font_size_12 nd_booking_letter_spacing_2\">La Min\u00e9rale &#8211; 17m\u00b2<\/a>\n                    <\/div>\n                <\/div>\n\n                <div class=\"nd_booking_position_absolute nd_booking_bottom_20 nd_booking_left_0 nd_booking_width_100_percentage\">\n\n\n                    <div class=\"nd_booking_section nd_booking_text_align_center nd_booking_display_none_iphone_port\">\n                        <div class=\"nd_booking_display_table nd_booking_margin_auto\">\n                            <img decoding=\"async\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"23\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-user-white.png\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\"> Guests<\/p>\n                            <img decoding=\"async\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_margin_left_20 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"20\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-plan-white.png\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\"> m\u00b2<\/p>\n                            <img decoding=\"async\" style=\"padding-bottom:4px;\" alt=\"\" class=\"nd_booking_margin_right_10 nd_booking_margin_left_20 nd_booking_display_table_cell nd_booking_vertical_align_middle\" width=\"20\" src=\"https:\/\/www.villamiami.fr\/wp-content\/plugins\/nd-booking\/addons\/visual\/rooms\/layout\/icon-star-empty-white.svg\">\n                            <p class=\" nd_booking_letter_spacing_2 nd_options_color_white nd_booking_display_table_cell nd_booking_vertical_align_middle nd_booking_font_size_12 nd_booking_line_height_26\">From  \u20ac<\/p>\n                        <\/div>\n                    <\/div> \n\n                <\/div>\n            <\/div>\n\n        <\/div>\n\n    \n\n        <\/div>\n\n    <\/div>\n\n<\/div><\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; parallax=&#8220;content-moving&#8220; parallax_image=&#8220;2401&#8243; css=&#8220;.vc_custom_1590683486582{margin-top: 100px !important;padding-top: 100px !important;padding-bottom: 100px !important;}&#8220; el_class=&#8220;nd_options_vc_parallax_filter_2_5&#8243;][vc_column width=&#8220;2\/3&#8243;]\n\n    <div class=\"nd_options_section nd_options_position_relative call_to_action_about_2\">\n\n        <img decoding=\"async\" style=\"top:5px\" alt=\"\" class=\"nd_options_position_absolute nd_options_left_0\" width=\"50\" src=\"https:\/\/www.villamiami.fr\/wp-content\/uploads\/2019\/05\/icon-checked-white.png\">\n\n        <div style=\"padding-left:70px\" class=\"nd_options_section nd_options_box_sizing_border_box\">\n            \n            <h3 class=\"nd_options_first_font underline_phone \" style=\"margin:;color:#ffffff;font-size:30px;line-height:30px\">KONTAKTIEREN SIE UNS ! <b>+33 (0)6 37 59 25 56<\/b><\/h3> \n            <p class=\"nd_options_second_font  \" style=\"margin:10px 0px 0px 0px;color:#ffffff;font-size:17px;line-height:27px\">Buchen Sie jetzt Ihr Zimmer<\/p> \n            \n\n        <\/div>\n\n    <\/div>\n\n  [\/vc_column][vc_column width=&#8220;1\/3&#8243;]<div style=\"background-color:;height: 8px\" class=\"nicdark_section  \"><\/div>\n\t<div class=\"nd_options_section nd_options_text_align_center\">\n\t<a style=\"border: 1px solid #ffffff;border-radius:px;letter-spacing:4px;line-height:11px;font-size:11px;background-color:;padding:15px 20px;margin:;color:#ffffff\" rel=\"\" href=\"https:\/\/www.villamiami.fr\/de\/contact-reservation\/\" class=\"nicdark_display_inline_block  nd_options_font_weight_lighter nd_options_second_font nd_options_disable_lateral_border nd_options_float_left_responsive \">RESERVIERUNG<\/a>\n\t<\/div>\n[\/vc_column][\/vc_row][vc_row equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; css=&#8220;.vc_custom_1589905386972{margin-top: 40px !important;background-color: #f9f9f9 !important;}&#8220;][vc_column]<div style=\"background-color:;height: 80px\" class=\"nicdark_section  \"><\/div> <h1 style=\"color:;padding:px;text-align:center;font-size:50px;line-height:px;letter-spacing: px;font-weight:lighter\" class=\"  nd_options_font_size_40_important_all_iphone nd_options_line_height_40_important_all_iphone nd_options_first_font \">AMBIOMANCE<\/h1> <div style=\"background-color:;height: 30px\" class=\"nicdark_section  \"><\/div> <p style=\"color:;padding:px;text-align:center;font-size:px;line-height:px;letter-spacing: 2px;font-weight:lighter\" class=\"  nd_options_font_size_40_important_all_iphone nd_options_line_height_40_important_all_iphone nd_options_second_font \">- VILLA MIAMI -<\/p> [\/vc_column][\/vc_row][vc_row equal_height=&#8220;yes&#8220; content_placement=&#8220;top&#8220; css=&#8220;.vc_custom_1589905673538{background-color: #f9f9f9 !important;}&#8220;][vc_column width=&#8220;1\/2&#8243;]<div style=\"background-color:;height: 50px\" class=\"nicdark_section  \"><\/div>[vc_column_text]Wir empfangen Sie bei uns zu Hause, in einem Haus, das wir nach einigen Entt\u00e4uschungen, einer verschlungenen Reise, aber Oh wie befriedigend, nach unserem Bild renoviert haben!<\/p>\n<p>Wir empfangen Sie als unsere G\u00e4ste, mit dem Respekt und der Freude, die man G\u00e4sten schuldet, und das auch dann, wenn es eine finanzielle Leistung gibt.<br \/>\nSie betreten eine Villa, die wir restauriert haben, um unseren G\u00e4sten ein H\u00f6chstma\u00df an Komfort und Ruhe zu bieten, wie wir sie als G\u00e4ste gerne h\u00e4tten.<br \/>\nWir m\u00f6chten Ihnen einen m\u00f6glichst unbeschwerten Aufenthalt erm\u00f6glichen![\/vc_column_text]<div style=\"background-color:;height: 20px\" class=\"nicdark_section  \"><\/div>[\/vc_column][vc_column width=&#8220;1\/2&#8243;]<div style=\"background-color:;height: 50px\" class=\"nicdark_section  \"><\/div>[vc_column_text]Die Villa ist zeitgem\u00e4\u00df und setzt unsere Philosophie fort. Die Musik, die rund um den Pool gespielt wird, ist Lounge-Musik im Stil von Deep House.<\/p>\n<p>Aber: Wir sind keine H\u00e4ndler. Nach einigen Entt\u00e4uschungen mit einigen G\u00e4sten m\u00f6chten wir klarstellen, dass die Villa rund um unsere Pers\u00f6nlichkeit, unsere Philosophie und das, was man von einem G\u00e4stezimmer am Meer im Urlaub erwarten m\u00f6chte, renoviert wurde. Es ist ein Ort, der unsere Geisteshaltung widerspiegelt: atypisch, au\u00dferhalb der gew\u00f6hnlichen Konventionen&#8230;[\/vc_column_text]<div style=\"background-color:;height: 30px\" class=\"nicdark_section  \"><\/div>[\/vc_column][\/vc_row][vc_row equal_height=&#8220;yes&#8220; content_placement=&#8220;top&#8220; css=&#8220;.vc_custom_1589905690221{background-color: #f9f9f9 !important;}&#8220;][vc_column width=&#8220;1\/2&#8243;][vc_column_text]<strong>Wir lieben es, wir hassen es Wir lieben es! Machen Sie es sich zur Aufgabe, diesen Ort ohne Anspr\u00fcche zu betreten, einfach nur neugierig zu sein, lassen Sie sich von dem Ort z\u00e4hmen und vielleicht finden Sie dort, wie wir, einen Ort, an dem man sich wohlf\u00fchlt, an dem man sich wie im Zen f\u00fchlt, an dem man sich niederlassen kann, ohne ihn verlassen zu wollen!<\/strong>[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/2&#8243;][vc_column_text]<strong>Die Lust zu bleiben, zur\u00fcckzukehren, andere zu entdecken&#8230;<\/strong><br \/>\n<strong>Die Lust, diese Freuden zu teilen, dort zu wohnen, eine Nacht, ein Wochenende oder mehr zu erleben!<\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row equal_height=&#8220;yes&#8220; content_placement=&#8220;top&#8220; css=&#8220;.vc_custom_1590683587870{background-color: #f9f9f9 !important;}&#8220;][vc_column]<div style=\"background-color:;height: 50px\" class=\"nicdark_section  \"><\/div>[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text] Entdecken Sie unsere 2 Suiten mit Whirlpool-Badewanne und unsere 3 Schlafzimmer : Die Matisse-Suite, die Vegetarische Suite, die Mineralien, die Schokolade und das Tauchen [\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row_content_no_spaces&#8220; css=&#8220;.vc_custom_1589902385613{margin-top: 30px !important;margin-bottom: 100px !important;}&#8220;][vc_column css=&#8220;.vc_custom_1491985274415{padding-right: 30px !important;padding-left: 30px !important;}&#8220;][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; parallax=&#8220;content-moving&#8220; parallax_image=&#8220;2401&#8243; css=&#8220;.vc_custom_1590683486582{margin-top: 100px !important;padding-top: 100px !important;padding-bottom: 100px !important;}&#8220; el_class=&#8220;nd_options_vc_parallax_filter_2_5&#8243;][vc_column width=&#8220;2\/3&#8243;][\/vc_column][vc_column width=&#8220;1\/3&#8243;][\/vc_column][\/vc_row][vc_row equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; css=&#8220;.vc_custom_1589905386972{margin-top: 40px !important;background-color: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4529","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.villamiami.fr\/de\/wp-json\/wp\/v2\/pages\/4529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.villamiami.fr\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.villamiami.fr\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.villamiami.fr\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.villamiami.fr\/de\/wp-json\/wp\/v2\/comments?post=4529"}],"version-history":[{"count":9,"href":"https:\/\/www.villamiami.fr\/de\/wp-json\/wp\/v2\/pages\/4529\/revisions"}],"predecessor-version":[{"id":5420,"href":"https:\/\/www.villamiami.fr\/de\/wp-json\/wp\/v2\/pages\/4529\/revisions\/5420"}],"wp:attachment":[{"href":"https:\/\/www.villamiami.fr\/de\/wp-json\/wp\/v2\/media?parent=4529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}